{"id":45,"date":"2025-03-17T10:42:47","date_gmt":"2025-03-17T09:42:47","guid":{"rendered":"https:\/\/www.le-mas-des-micocouliers.fr\/?page_id=45"},"modified":"2025-04-09T22:09:14","modified_gmt":"2025-04-09T20:09:14","slug":"accueil","status":"publish","type":"page","link":"https:\/\/www.le-mas-des-micocouliers.fr\/en\/","title":{"rendered":"Accueil"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-45","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accueil - Le Mas des Micocouliers<\/title>\n<meta name=\"description\" content=\"Mas proven\u00e7al restaur\u00e9 \u00e0 Aix-en-Provence. S\u00e9jours nature ou culture, h\u00e9bergements de charme, calme et convivialit\u00e9 au c\u0153ur de la Provence.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.le-mas-des-micocouliers.fr\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Mas des Micocouliers \u2013 S\u00e9jours de charme en Provence\" \/>\n<meta property=\"og:description\" content=\"Mas proven\u00e7al du XIXe si\u00e8cle pr\u00e8s d\u2019Aix-en-Provence. S\u00e9jours nature ou culture, h\u00e9bergements authentiques et grande piscine arbor\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.le-mas-des-micocouliers.fr\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Mas des Micocouliers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/masmicocouliers\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-09T20:09:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.le-mas-des-micocouliers.fr\/wp-content\/uploads\/2025\/04\/Mas-Des-Micocouliers-Slider-1-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1199\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/\",\"url\":\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/\",\"name\":\"Accueil - Le Mas des Micocouliers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/#website\"},\"datePublished\":\"2025-03-17T09:42:47+00:00\",\"dateModified\":\"2025-04-09T20:09:14+00:00\",\"description\":\"Mas proven\u00e7al restaur\u00e9 \u00e0 Aix-en-Provence. S\u00e9jours nature ou culture, h\u00e9bergements de charme, calme et convivialit\u00e9 au c\u0153ur de la Provence.\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/\",\"name\":\"Le Mas des Micocouliers \u2013 S\u00e9jours de charme en Provence\",\"description\":\"S\u00e9journez dans un mas d\u2019exception au sud d&#039;Aix-en-Provence\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/#organization\"},\"alternateName\":\"Le Mas des Micocouliers \u2013 S\u00e9jours de charme en Provence\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/#organization\",\"name\":\"Le Mas des Micocouliers\",\"alternateName\":\"Le Mas des Micocouliers\",\"url\":\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Le Mas des Micocouliers\"},\"image\":{\"@id\":\"https:\\\/\\\/www.le-mas-des-micocouliers.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/masmicocouliers\",\"https:\\\/\\\/www.instagram.com\\\/masmicocouliers\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueil - Le Mas des Micocouliers","description":"Mas proven\u00e7al restaur\u00e9 \u00e0 Aix-en-Provence. S\u00e9jours nature ou culture, h\u00e9bergements de charme, calme et convivialit\u00e9 au c\u0153ur de la Provence.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.le-mas-des-micocouliers.fr\/en\/","og_locale":"en_GB","og_type":"article","og_title":"Le Mas des Micocouliers \u2013 S\u00e9jours de charme en Provence","og_description":"Mas proven\u00e7al du XIXe si\u00e8cle pr\u00e8s d\u2019Aix-en-Provence. S\u00e9jours nature ou culture, h\u00e9bergements authentiques et grande piscine arbor\u00e9e.","og_url":"https:\/\/www.le-mas-des-micocouliers.fr\/en\/","og_site_name":"Le Mas des Micocouliers","article_publisher":"https:\/\/www.facebook.com\/masmicocouliers","article_modified_time":"2025-04-09T20:09:14+00:00","og_image":[{"width":2560,"height":1199,"url":"https:\/\/www.le-mas-des-micocouliers.fr\/wp-content\/uploads\/2025\/04\/Mas-Des-Micocouliers-Slider-1-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.le-mas-des-micocouliers.fr\/","url":"https:\/\/www.le-mas-des-micocouliers.fr\/","name":"Accueil - Le Mas des Micocouliers","isPartOf":{"@id":"https:\/\/www.le-mas-des-micocouliers.fr\/#website"},"datePublished":"2025-03-17T09:42:47+00:00","dateModified":"2025-04-09T20:09:14+00:00","description":"Mas proven\u00e7al restaur\u00e9 \u00e0 Aix-en-Provence. S\u00e9jours nature ou culture, h\u00e9bergements de charme, calme et convivialit\u00e9 au c\u0153ur de la Provence.","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.le-mas-des-micocouliers.fr\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.le-mas-des-micocouliers.fr\/#website","url":"https:\/\/www.le-mas-des-micocouliers.fr\/","name":"Le Mas des Micocouliers \u2013 S\u00e9jours de charme en Provence","description":"S\u00e9journez dans un mas d\u2019exception au sud d&#039;Aix-en-Provence","publisher":{"@id":"https:\/\/www.le-mas-des-micocouliers.fr\/#organization"},"alternateName":"Le Mas des Micocouliers \u2013 S\u00e9jours de charme en Provence","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.le-mas-des-micocouliers.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.le-mas-des-micocouliers.fr\/#organization","name":"Le Mas des Micocouliers","alternateName":"Le Mas des Micocouliers","url":"https:\/\/www.le-mas-des-micocouliers.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.le-mas-des-micocouliers.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.le-mas-des-micocouliers.fr\/wp-content\/uploads\/2025\/03\/favicon.png","contentUrl":"https:\/\/www.le-mas-des-micocouliers.fr\/wp-content\/uploads\/2025\/03\/favicon.png","width":512,"height":512,"caption":"Le Mas des Micocouliers"},"image":{"@id":"https:\/\/www.le-mas-des-micocouliers.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/masmicocouliers","https:\/\/www.instagram.com\/masmicocouliers\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.le-mas-des-micocouliers.fr\/en\/wp-json\/wp\/v2\/pages\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.le-mas-des-micocouliers.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.le-mas-des-micocouliers.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.le-mas-des-micocouliers.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.le-mas-des-micocouliers.fr\/en\/wp-json\/wp\/v2\/comments?post=45"}],"version-history":[{"count":2,"href":"https:\/\/www.le-mas-des-micocouliers.fr\/en\/wp-json\/wp\/v2\/pages\/45\/revisions"}],"predecessor-version":[{"id":89,"href":"https:\/\/www.le-mas-des-micocouliers.fr\/en\/wp-json\/wp\/v2\/pages\/45\/revisions\/89"}],"wp:attachment":[{"href":"https:\/\/www.le-mas-des-micocouliers.fr\/en\/wp-json\/wp\/v2\/media?parent=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}